{"id":2252,"date":"2025-09-30T14:11:09","date_gmt":"2025-09-30T12:11:09","guid":{"rendered":"https:\/\/pete-ai.com\/?p=2252"},"modified":"2025-09-30T14:11:10","modified_gmt":"2025-09-30T12:11:10","slug":"hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89","status":"publish","type":"post","link":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/","title":{"rendered":"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89"},"content":{"rendered":"<div class=\"container\">\n<p class=\"wp-block-paragraph\">Wir freuen uns riesig: Hey PETE! wurde im August 2025 von der WirtschaftsWoche beim renommierten Best of Technology Award in M\u00fcnchen mit dem Pr\u00e4dikat \u201eExcellent\u201c ausgezeichnet.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p class=\"wp-block-paragraph\">Aus 110 Bewerbern schafften es nur 40 Unternehmen ins Finale \u2013 und Hey PETE! war mittendrin. F\u00fcr uns ist das bereits ein riesiger Erfolg und eine Best\u00e4tigung f\u00fcr unsere Arbeit im Bereich IT Service Management (ITSM) und Prozessmanagement.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p class=\"wp-block-paragraph\">Das Besondere: Mit unserem LLM-powered ITSM Process Scoring stand Hey PETE! auf der gro\u00dfen B\u00fchne des Prozessmanagements \u2013 genau dort, wo es hingeh\u00f6rt.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p class=\"wp-block-paragraph\">Ein riesiges Dankesch\u00f6n an unser gro\u00dfartiges PETE-Team \u2013 dieser Award ist f\u00fcr euch! \ud83d\udc9a\ud83e\udd42<\/p>\n<\/div>\n\n<div class=\"container\">\n<p class=\"wp-block-paragraph\">\ud83d\udc49 Mit Hey PETE! erm\u00f6glichen wir Unternehmen, ihre ITSM-Prozesse messbar, transparent und zukunftssicher zu machen.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wir freuen uns riesig: Hey PETE! wurde im August 2025 von der WirtschaftsWoche beim renommierten Best of Technology Award in M\u00fcnchen mit dem Pr\u00e4dikat \u201eExcellent\u201c ausgezeichnet. Aus 110 Bewerbern schafften es nur 40 Unternehmen ins Finale \u2013 und Hey PETE! war mittendrin. F\u00fcr uns ist das bereits ein riesiger Erfolg und eine Best\u00e4tigung f\u00fcr unsere [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2250,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erfolge-und-auszeichnungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89 - Pete AI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-\ud83c\udf89\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89 - Pete AI\" \/>\n<meta property=\"og:description\" content=\"Wir freuen uns riesig: Hey PETE! wurde im August 2025 von der WirtschaftsWoche beim renommierten Best of Technology Award in M\u00fcnchen mit dem Pr\u00e4dikat \u201eExcellent\u201c ausgezeichnet. Aus 110 Bewerbern schafften es nur 40 Unternehmen ins Finale \u2013 und Hey PETE! war mittendrin. F\u00fcr uns ist das bereits ein riesiger Erfolg und eine Best\u00e4tigung f\u00fcr unsere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-\ud83c\udf89\/\" \/>\n<meta property=\"og:site_name\" content=\"Pete AI\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T12:11:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T12:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pete-ai.com\/wp-content\/uploads\/2025\/09\/Best-of-Technology-Blog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1338\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Chrissi Vitt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chrissi Vitt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/\"},\"author\":{\"name\":\"Chrissi Vitt\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#\\\/schema\\\/person\\\/08e339ef522839810c460cba4a358d2b\"},\"headline\":\"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89\",\"datePublished\":\"2025-09-30T12:11:09+00:00\",\"dateModified\":\"2025-09-30T12:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/\"},\"wordCount\":130,\"publisher\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pete-ai.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Best-of-Technology-Blog.png\",\"articleSection\":[\"\ud83c\udfc6 Erfolge &amp; Auszeichnungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/\",\"url\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/\",\"name\":\"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89 - Pete AI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pete-ai.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Best-of-Technology-Blog.png\",\"datePublished\":\"2025-09-30T12:11:09+00:00\",\"dateModified\":\"2025-09-30T12:11:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pete-ai.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Best-of-Technology-Blog.png\",\"contentUrl\":\"https:\\\/\\\/pete-ai.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Best-of-Technology-Blog.png\",\"width\":1338,\"height\":776},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#website\",\"url\":\"https:\\\/\\\/pete-ai.com\\\/\",\"name\":\"Pete AI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pete-ai.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#organization\",\"name\":\"Pete AI\",\"url\":\"https:\\\/\\\/pete-ai.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pete-ai.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pete.svg\",\"contentUrl\":\"https:\\\/\\\/pete-ai.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pete.svg\",\"caption\":\"Pete AI\"},\"image\":{\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pete-ai.com\\\/#\\\/schema\\\/person\\\/08e339ef522839810c460cba4a358d2b\",\"name\":\"Chrissi Vitt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f440cb5595a698371eef7958e5ddfee0f3d6de801fd360340716c29d25ed058a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f440cb5595a698371eef7958e5ddfee0f3d6de801fd360340716c29d25ed058a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f440cb5595a698371eef7958e5ddfee0f3d6de801fd360340716c29d25ed058a?s=96&d=mm&r=g\",\"caption\":\"Chrissi Vitt\"},\"sameAs\":[\"https:\\\/\\\/pete-ai.com\\\/\"],\"url\":\"https:\\\/\\\/pete-ai.com\\\/de\\\/author\\\/chrissi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89 - Pete AI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-\ud83c\udf89\/","og_locale":"de_DE","og_type":"article","og_title":"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89 - Pete AI","og_description":"Wir freuen uns riesig: Hey PETE! wurde im August 2025 von der WirtschaftsWoche beim renommierten Best of Technology Award in M\u00fcnchen mit dem Pr\u00e4dikat \u201eExcellent\u201c ausgezeichnet. Aus 110 Bewerbern schafften es nur 40 Unternehmen ins Finale \u2013 und Hey PETE! war mittendrin. F\u00fcr uns ist das bereits ein riesiger Erfolg und eine Best\u00e4tigung f\u00fcr unsere [&hellip;]","og_url":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-\ud83c\udf89\/","og_site_name":"Pete AI","article_published_time":"2025-09-30T12:11:09+00:00","article_modified_time":"2025-09-30T12:11:10+00:00","og_image":[{"width":1338,"height":776,"url":"https:\/\/pete-ai.com\/wp-content\/uploads\/2025\/09\/Best-of-Technology-Blog.png","type":"image\/png"}],"author":"Chrissi Vitt","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Chrissi Vitt","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/#article","isPartOf":{"@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/"},"author":{"name":"Chrissi Vitt","@id":"https:\/\/pete-ai.com\/#\/schema\/person\/08e339ef522839810c460cba4a358d2b"},"headline":"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89","datePublished":"2025-09-30T12:11:09+00:00","dateModified":"2025-09-30T12:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/"},"wordCount":130,"publisher":{"@id":"https:\/\/pete-ai.com\/#organization"},"image":{"@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/#primaryimage"},"thumbnailUrl":"https:\/\/pete-ai.com\/wp-content\/uploads\/2025\/09\/Best-of-Technology-Blog.png","articleSection":["\ud83c\udfc6 Erfolge &amp; Auszeichnungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/","url":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/","name":"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89 - Pete AI","isPartOf":{"@id":"https:\/\/pete-ai.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/#primaryimage"},"image":{"@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/#primaryimage"},"thumbnailUrl":"https:\/\/pete-ai.com\/wp-content\/uploads\/2025\/09\/Best-of-Technology-Blog.png","datePublished":"2025-09-30T12:11:09+00:00","dateModified":"2025-09-30T12:11:10+00:00","breadcrumb":{"@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/#primaryimage","url":"https:\/\/pete-ai.com\/wp-content\/uploads\/2025\/09\/Best-of-Technology-Blog.png","contentUrl":"https:\/\/pete-ai.com\/wp-content\/uploads\/2025\/09\/Best-of-Technology-Blog.png","width":1338,"height":776},{"@type":"BreadcrumbList","@id":"https:\/\/pete-ai.com\/de\/hey-pete-erhaelt-auszeichnung-beim-best-of-technology-award-2025-%f0%9f%8e%89\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/pete-ai.com\/de\/"},{"@type":"ListItem","position":2,"name":"Hey PETE! erh\u00e4lt Auszeichnung beim Best of Technology Award 2025 \ud83c\udf89"}]},{"@type":"WebSite","@id":"https:\/\/pete-ai.com\/#website","url":"https:\/\/pete-ai.com\/","name":"Pete AI","description":"","publisher":{"@id":"https:\/\/pete-ai.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pete-ai.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/pete-ai.com\/#organization","name":"Pete AI","url":"https:\/\/pete-ai.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pete-ai.com\/#\/schema\/logo\/image\/","url":"https:\/\/pete-ai.com\/wp-content\/uploads\/2024\/09\/pete.svg","contentUrl":"https:\/\/pete-ai.com\/wp-content\/uploads\/2024\/09\/pete.svg","caption":"Pete AI"},"image":{"@id":"https:\/\/pete-ai.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pete-ai.com\/#\/schema\/person\/08e339ef522839810c460cba4a358d2b","name":"Chrissi Vitt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f440cb5595a698371eef7958e5ddfee0f3d6de801fd360340716c29d25ed058a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f440cb5595a698371eef7958e5ddfee0f3d6de801fd360340716c29d25ed058a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f440cb5595a698371eef7958e5ddfee0f3d6de801fd360340716c29d25ed058a?s=96&d=mm&r=g","caption":"Chrissi Vitt"},"sameAs":["https:\/\/pete-ai.com\/"],"url":"https:\/\/pete-ai.com\/de\/author\/chrissi\/"}]}},"_links":{"self":[{"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/posts\/2252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/comments?post=2252"}],"version-history":[{"count":1,"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/posts\/2252\/revisions"}],"predecessor-version":[{"id":2253,"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/posts\/2252\/revisions\/2253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/media\/2250"}],"wp:attachment":[{"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/media?parent=2252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/categories?post=2252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pete-ai.com\/de\/wp-json\/wp\/v2\/tags?post=2252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}